{"id":8157,"date":"2022-11-04T15:56:51","date_gmt":"2022-11-04T14:56:51","guid":{"rendered":"https:\/\/www.dyrecta.com\/lab\/?p=8157"},"modified":"2022-11-04T16:06:48","modified_gmt":"2022-11-04T15:06:48","slug":"nuova-pubblicazione-di-dyrecta-lab-dal-titolo-developing-and-preliminary-testing-of-a-machine-learning-based-platform-for-sales-forecasting-using-a-gradient-boosting-approach","status":"publish","type":"post","link":"https:\/\/www.dyrecta.com\/lab\/nuova-pubblicazione-di-dyrecta-lab-dal-titolo-developing-and-preliminary-testing-of-a-machine-learning-based-platform-for-sales-forecasting-using-a-gradient-boosting-approach\/","title":{"rendered":"Nuova pubblicazione di Dyrecta Lab  dal titolo &#8220;Developing and Preliminary Testing of a Machine Learning-Based Platform for Sales Forecasting Using a Gradient Boosting Approach&#8221;"},"content":{"rendered":"<p style=\"font-weight: 400;\"><strong>Le aziende che utilizzano siti di e-commerce, indipendentemente dal settore in cui operano, devono essere in grado di estrarre conoscenza dai dati a loro disposizione.<\/strong> Spesso il volume dei dati di clienti e fornitori \u00e8 cos\u00ec grande che \u00e8 necessario l&#8217;uso di algoritmi di data mining avanzati. In particolare, gli algoritmi di autoapprendimento (machine learning) consentono di costruire modelli predittivi al fine di prevedere la domanda dei clienti e, di conseguenza, ottimizzare la gestione delle forniture e della logistica di magazzino.<\/p>\n<p style=\"font-weight: 400;\">La trasformazione tecnologica e digitale che si \u00e8 verificata negli ultimi anni ha determinato l&#8217;espansione del commercio online, consentono alle aziende di implementare una strategia di vendita omnicanale. Nasce quindi l&#8217;esigenza di gestire i vari canali di vendita e le varie filiali di un&#8217;azienda.<\/p>\n<p style=\"font-weight: 400;\"><strong>Questa ricerca ha studiato l&#8217;applicabilit\u00e0 e le prestazioni di approcci basati su tecniche di machine learning in un caso di studio relativo alla previsione delle vendite in un contesto multi store e multicanale.<\/strong><\/p>\n<p style=\"font-weight: 400;\">L&#8217;output dell&#8217;approccio sviluppato aiuta un&#8217;azienda di e-commerce ad automatizzare i propri processi interni e ottimizzare i flussi di lavoro.<\/p>\n<p style=\"font-weight: 400;\">L&#8217;innovazione IT permette di interagire in maniera ottimale con i consumatori di oggi sempre pi\u00f9 connessi a Internet. I moderni strumenti tecnologici offrono agli utenti esperienze di acquisto altamente personalizzate su ogni canale di vendita.<\/p>\n<p style=\"font-weight: 400;\">Le aziende attraverso l&#8217;analisi dei dati possono offrire una migliore esperienza al cliente, con servizi pi\u00f9 veloci, pi\u00f9 affidabili e una migliore efficienza operativa.<\/p>\n<p style=\"font-weight: 400;\"><strong>Durante lo svolgimento dello studio di ricerca \u00e8 stato implementato e validato un modello predittivo basato sull\u2019algoritmo di XGBoost.<\/strong><\/p>\n<p style=\"font-weight: 400;\">I test effettuati permettono di concludere che il modello di XGBoost implementato \u00e8 molto accurato nel prevedere le vendite future. La precisione del modello \u00e8 stata misurata in termini di varie metriche di accuratezza, come MSE (Mean Square Error), MAE (Mean Absolute Error), MAPE (Mean Absolute Percentage Error) e WAPE (Errore percentuale assoluta ponderata).<\/p>\n<p>Scarica la Pubblicazione:<br \/>\n<a href=\"https:\/\/www.dyrecta.com\/lab\/wp-content\/uploads\/2022\/11\/applsci-12-11054.pdf\">applsci-12-11054<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le aziende che utilizzano siti di e-commerce, indipendentemente dal settore in cui operano, devono essere in grado di estrarre conoscenza&#8230;<\/p>\n","protected":false},"author":1,"featured_media":8158,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,42],"tags":[],"_links":{"self":[{"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/posts\/8157"}],"collection":[{"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/comments?post=8157"}],"version-history":[{"count":3,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/posts\/8157\/revisions"}],"predecessor-version":[{"id":8162,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/posts\/8157\/revisions\/8162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/media\/8158"}],"wp:attachment":[{"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/media?parent=8157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/categories?post=8157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/tags?post=8157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}