{"id":7015,"date":"2021-05-04T17:02:02","date_gmt":"2021-05-04T15:02:02","guid":{"rendered":"https:\/\/dyrecta.com\/lab\/?p=7015"},"modified":"2021-05-05T13:25:47","modified_gmt":"2021-05-05T11:25:47","slug":"industria-40-interconnessione-tra-le-macchine-con-gli-applicativi-mes","status":"publish","type":"post","link":"https:\/\/www.dyrecta.com\/lab\/industria-40-interconnessione-tra-le-macchine-con-gli-applicativi-mes\/","title":{"rendered":"INDUSTRIA 4.0: l\u2019interconnessione tra le macchine con gli applicativi MES."},"content":{"rendered":"<p style=\"text-align: left;\">Per <strong>interconnessione<\/strong> s\u2019intende un\u2019evoluzione delle tecnologie digitali che portano ad un potenziale cambio di paradigma caratterizzato da una\u00a0maggiore <strong>cooperazione<\/strong> <strong>tra impianti, persone e informazioni<\/strong>, sia dentro la fabbrica che lungo la catena del valore.<\/p>\n<p>Si tratta di un processo di <strong>trasformazione digitale<\/strong> di enorme portata che riguarda l\u2019utilizzo dell\u2019<strong>informatica<\/strong> e dell\u2019<strong>automazione<\/strong> e comprende sia la manifattura che tutti gli attori che entrano a far parte della catena di valore.<\/p>\n<p>D\u2019altro canto questo paradigma ha messo i punti di debolezza della digitalizzazione del sistema produttivo italiano in quanto un numero limitato di aziende \u00e8 in grado di coordinare il processo evolutivo delle catene di fornitura e sub-fornitura.<\/p>\n<p>Affinch\u00e8 funzioni, il sistema interconnesso deve scambiare informazioni col sistema gestionale, i sistemi di controllo dell\u2019automazione industriale e il magazzino, garantendo naturalmente la sicurezza delle informazioni.<\/p>\n<p><strong>Il concetto di interconnessione \u00e8 di primaria importanza per l\u2019Industria 4.0<\/strong> e, seppur sia una caratteristica esterna al macchinario, \u00e8 obbligatoria in quanto fondamentale alla raccolta dei dati, l\u2019analisi e la valutazione delle performance produttive.<\/p>\n<p>Per interconnettere una fabbrica occorre introdurre soluzioni in grado di fare un\u2019integrazione comune dei diversi componenti, moduli e sistemi creando un legame biunivoco tra le macchine: i <strong>software MES<\/strong>.<\/p>\n<p>Semplificando i <strong>Manufacturing Execution System<\/strong> sono sistemi informatici utilizzati nelle industrie manifatturiere per monitorare, controllare e documentare la trasformazione delle materie prime in prodotti finiti con lo scopo di migliorare il processo produttivo, collegando informazioni in tempo reale di impianti, stabilimenti e fornitori.<\/p>\n<p>Il MES, o MOM (Manufacturing Execution System) come ridefinito dallo standard <strong>ISA 95<\/strong>, \u00e8 uno strumento strategico per la flessibilit\u00e0 di ogni sistema produttivo, che risponde alla sempre maggiore richiesta di mercato di un alto livello di customizzazione che solo un sistema efficiente di gestione in tempo reale dei dati consente di creare.<\/p>\n<p>Integrazione e interconnessione sono le peculiarit\u00e0 indispensabili allo sviluppo di un ecosistema in logica Industria 4.0 ed il\u00a0<strong>MES<\/strong>\u00a0<strong>\u00e8 l\u2019elemento centrale attorno al quale implementare la digitalizzazione della manifattura<\/strong>\u00a0in\u00a0varie aree: logistica, pianificazione, gestione e monitoraggio della produzione, manutenzione, qualit\u00e0, tracciabilit\u00e0 di processo e di prodotto ed altre ancora.<\/p>\n<p><a href=\"https:\/\/www.dyrecta.com\/lab\/wp-content\/uploads\/2021\/05\/Tecne_Datalogic_1_31.03.2016.jpg\"><img loading=\"lazy\" class=\"wp-image-7032 aligncenter\" src=\"https:\/\/www.dyrecta.com\/lab\/wp-content\/uploads\/2021\/05\/Tecne_Datalogic_1_31.03.2016-300x182.jpg\" alt=\"\" width=\"769\" height=\"467\" srcset=\"https:\/\/www.dyrecta.com\/lab\/wp-content\/uploads\/2021\/05\/Tecne_Datalogic_1_31.03.2016-300x182.jpg 300w, https:\/\/www.dyrecta.com\/lab\/wp-content\/uploads\/2021\/05\/Tecne_Datalogic_1_31.03.2016.jpg 530w\" sizes=\"(max-width: 769px) 100vw, 769px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><em>Schema di un sistema interconnesso di processi tecnici produttivi e gestione d&#8217;impresa.<\/em><\/p>\n<p>Il MES, integrato con i sistemi ERP e i gestionali aziendali e ai sistemi PLM (Product Lifecycle Management), consente di analizzare ogni \u201canello\u201d della catena di valore, monitorando inventario, ordini e risorse, attivit\u00e0 svolte e attori coinvolti e identificando velocemente la causa degli errori per interventi tempestivi.<\/p>\n<p>I <strong>vantaggi<\/strong> dell\u2019implementazione di un MES sono:<\/p>\n<ul>\n<li>Maggiore rapidit\u00e0 di messa in produzione di nuovi prodotti<\/li>\n<li>Maggiore flessibilit\u00e0 nello sviluppo di prodotti personalizzati<\/li>\n<li>Gestione rapida di problemi o richiami<\/li>\n<li>Aumento della capacit\u00e0 produttiva<\/li>\n<li>Riduzione dei fermo-macchina<\/li>\n<li>Riduzione degli sprechi<\/li>\n<li>Maggiore capacit\u00e0 di coordinamento<\/li>\n<li>Riduzione dei costi<\/li>\n<\/ul>\n<p><strong>La\u00a0causa pi\u00f9 frequente che impedisce alle aziende di godere degli incentivi<\/strong><strong>\u00a0<\/strong>connessi agli\u00a0<strong>investimenti 4.0<\/strong>\u00a0\u00e8 imputabile all\u2019<strong>assenza di piattaforme<\/strong>\u00a0necessarie a garantire la gestione dei dati di produzione.<\/p>\n<p>Prima di intraprendere la strada di conversione a Industria 4.0 \u00e8 dunque necessaria un\u2019attenta analisi di tutti i processi aziendali e la <strong>mappatura del flusso di valore<\/strong>, definendo lo stato attuale, &#8220;<strong>as is<\/strong>&#8221; e il \u201c<strong>to be\u201d<\/strong>, cio\u00e8 gli obiettivi che si intendono raggiungere, individuando le aree prioritarie di intervento.<\/p>\n<p>Ogni azienda ha le sue priorit\u00e0: per alcune sar\u00e0 pi\u00f9 importante l\u2019implementazione di sistemi per il <strong>monitoraggio della produzione<\/strong>, per altre la <strong>manutenzione predittiva<\/strong> o la <strong>tracciabilit\u00e0<\/strong> di processo e e di prodotto.<\/p>\n<p><a href=\"https:\/\/www.dyrecta.com\/lab\/\">Dyrecta lab<\/a> in qualit\u00e0 di Istituto di Ricerca e Centro di Trasferimento Tecnologico, supporta le aziende nei processi di conversione a <a href=\"https:\/\/www.dyrecta.com\/lab\/industria-4-0-come-cambiera-il-modo-di-lavorare-e-produrre\/\">Industria 4.0<\/a> e ha sviluppato progetti di interconnessione per aziende manifatturiere di ogni settore.<\/p>\n<p><a href=\"https:\/\/www.dyrecta.com\/lab\/contatti-2\/\">Richiedi info<\/a><\/p>\n<p>Leggi anche:<\/p>\n<p><a href=\"https:\/\/www.dyrecta.com\/lab\/agevolazioni-credito-dimposta-4-0-per-investimenti-in-beni-strumentali-nuovi-ex-iperammortamento\/\">Credito d&#8217;imposta per investimenti in beni strumentali<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per interconnessione s\u2019intende un\u2019evoluzione delle tecnologie digitali che portano ad un potenziale cambio di paradigma caratterizzato da una\u00a0maggiore cooperazione tra&#8230;<\/p>\n","protected":false},"author":5,"featured_media":7021,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[97],"tags":[],"_links":{"self":[{"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/posts\/7015"}],"collection":[{"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/comments?post=7015"}],"version-history":[{"count":13,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/posts\/7015\/revisions"}],"predecessor-version":[{"id":7037,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/posts\/7015\/revisions\/7037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/media\/7021"}],"wp:attachment":[{"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/media?parent=7015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/categories?post=7015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/tags?post=7015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}