{"id":3974,"date":"2019-10-29T16:18:14","date_gmt":"2019-10-29T15:18:14","guid":{"rendered":"https:\/\/dyrecta.com\/lab\/?p=3974"},"modified":"2019-10-29T16:22:41","modified_gmt":"2019-10-29T15:22:41","slug":"prossima-partecipazione-al-forum-le-nuove-frontiere-dellit-in-puglia","status":"publish","type":"post","link":"https:\/\/www.dyrecta.com\/lab\/prossima-partecipazione-al-forum-le-nuove-frontiere-dellit-in-puglia\/","title":{"rendered":"Prossima partecipazione al Forum &#8220;Le nuove frontiere dell&#8217;IT in Puglia&#8221;"},"content":{"rendered":"<p>Dyrecta Lab parteciper\u00e0 al forum <strong>&#8220;Le nuove frontiere dell&#8217;IT in Puglia&#8221;<\/strong>, che si terr\u00e0 ad <strong>Ostuni il 7-8 novembre 2019<\/strong>. Gioved\u00ec 7 Novembre interverr\u00e0 il prof. Alessandro Massaro, nella sessione &#8220;Sicurezza e utenti finali&#8221;, sul tema dal titolo<em> &#8220;Progettazione e sviluppo di progetti di ricerca orientati ai sistemi di supporto alle decisioni con intelligenza artificiale per la tutela delle risorse idriche, per il monitoraggio di rischio idrogeologico e nei processi di telemedicina della regione Puglia&#8221;<\/em>.<br \/>\nPer partecipare a questo evento, \u00e8 possibile registrarsi al portale della Regione Puglia: <a href=\"http:\/\/internazionalizzazione.regione.puglia.it\/partecipa-agli-eventi\" target=\"_blank\">http:\/\/internazionalizzazione.regione.puglia.it\/partecipa-agli-eventi<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dyrecta Lab parteciper\u00e0 al forum &#8220;Le nuove frontiere dell&#8217;IT in Puglia&#8221;, che si terr\u00e0 ad Ostuni il 7-8 novembre 2019&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":3871,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/posts\/3974"}],"collection":[{"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/comments?post=3974"}],"version-history":[{"count":4,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/posts\/3974\/revisions"}],"predecessor-version":[{"id":3978,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/posts\/3974\/revisions\/3978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/media\/3871"}],"wp:attachment":[{"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/media?parent=3974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/categories?post=3974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dyrecta.com\/lab\/wp-json\/wp\/v2\/tags?post=3974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}